{"id":4886,"date":"2022-11-11T12:33:58","date_gmt":"2022-11-11T12:33:58","guid":{"rendered":"http:\/\/localhost\/opstina\/?page_id=4886"},"modified":"2025-12-02T13:28:01","modified_gmt":"2025-12-02T13:28:01","slug":"uslugi","status":"publish","type":"page","link":"https:\/\/kicevo.gov.mk\/sq\/uslugi\/","title":{"rendered":"Sh\u00ebrbimet"},"content":{"rendered":"\n<p><a href=\"https:\/\/kicevo.gov.mk\/sq\/formulari\/\">Formular\u00ebt<\/a><br><a href=\"https:\/\/kicevo.gov.mk\/sq\/sluzhben-glasnik\/\">Fletorja Zyrtare<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Formular\u00ebtFletorja Zyrtare<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/sidebar-right.php","meta":{"_uag_custom_page_level_css":"","_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-4886","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"sq","enabled_languages":["mk","sq"],"languages":{"mk":{"title":true,"content":true,"excerpt":false},"sq":{"title":true,"content":true,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sh\u00ebrbimet | Komuna e K\u00ebr\u00e7ov\u00ebs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kicevo.gov.mk\/sq\/uslugi\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sh\u00ebrbimet | Komuna e K\u00ebr\u00e7ov\u00ebs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kicevo.gov.mk\/sq\/uslugi\/\" \/>\n<meta property=\"og:site_name\" content=\"Komuna e K\u00ebr\u00e7ov\u00ebs\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-02T13:28:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/uslugi\\\/\",\"url\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/uslugi\\\/\",\"name\":\"Sh\u00ebrbimet | Komuna e K\u00ebr\u00e7ov\u00ebs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/#website\"},\"datePublished\":\"2022-11-11T12:33:58+00:00\",\"dateModified\":\"2025-12-02T13:28:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/uslugi\\\/#breadcrumb\"},\"inLanguage\":\"sq\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/uslugi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/uslugi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u041f\u043e\u0447\u0435\u0442\u043d\u0430\",\"item\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sh\u00ebrbimet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/#website\",\"url\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/\",\"name\":\"\u041e\u043f\u0448\u0442\u0438\u043d\u0430 \u041a\u0438\u0447\u0435\u0432\u043e\",\"description\":\"Mir\u00eb se erdh\u00ebt n\u00eb ueb faqen zyrtare t\u00eb Komun\u00ebs s\u00eb K\u00ebr\u00e7ov\u00ebs\",\"publisher\":{\"@id\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/#organization\",\"name\":\"Opstina Kicevo\",\"url\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq\",\"@id\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kicevo.gov.mk\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-alb.png\",\"contentUrl\":\"https:\\\/\\\/kicevo.gov.mk\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-alb.png\",\"width\":1200,\"height\":1592,\"caption\":\"Opstina Kicevo\"},\"image\":{\"@id\":\"https:\\\/\\\/kicevo.gov.mk\\\/sq\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sh\u00ebrbimet | Komuna e K\u00ebr\u00e7ov\u00ebs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kicevo.gov.mk\/sq\/uslugi\/","og_locale":"sq_AL","og_type":"article","og_title":"Sh\u00ebrbimet | Komuna e K\u00ebr\u00e7ov\u00ebs","og_url":"https:\/\/kicevo.gov.mk\/sq\/uslugi\/","og_site_name":"Komuna e K\u00ebr\u00e7ov\u00ebs","article_modified_time":"2025-12-02T13:28:01+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kicevo.gov.mk\/sq\/uslugi\/","url":"https:\/\/kicevo.gov.mk\/sq\/uslugi\/","name":"Sh\u00ebrbimet | Komuna e K\u00ebr\u00e7ov\u00ebs","isPartOf":{"@id":"https:\/\/kicevo.gov.mk\/sq\/#website"},"datePublished":"2022-11-11T12:33:58+00:00","dateModified":"2025-12-02T13:28:01+00:00","breadcrumb":{"@id":"https:\/\/kicevo.gov.mk\/sq\/uslugi\/#breadcrumb"},"inLanguage":"sq","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kicevo.gov.mk\/sq\/uslugi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kicevo.gov.mk\/sq\/uslugi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u041f\u043e\u0447\u0435\u0442\u043d\u0430","item":"https:\/\/kicevo.gov.mk\/sq\/"},{"@type":"ListItem","position":2,"name":"Sh\u00ebrbimet"}]},{"@type":"WebSite","@id":"https:\/\/kicevo.gov.mk\/sq\/#website","url":"https:\/\/kicevo.gov.mk\/sq\/","name":"\u041e\u043f\u0448\u0442\u0438\u043d\u0430 \u041a\u0438\u0447\u0435\u0432\u043e","description":"Mir\u00eb se erdh\u00ebt n\u00eb ueb faqen zyrtare t\u00eb Komun\u00ebs s\u00eb K\u00ebr\u00e7ov\u00ebs","publisher":{"@id":"https:\/\/kicevo.gov.mk\/sq\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kicevo.gov.mk\/sq\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq"},{"@type":"Organization","@id":"https:\/\/kicevo.gov.mk\/sq\/#organization","name":"Opstina Kicevo","url":"https:\/\/kicevo.gov.mk\/sq\/","logo":{"@type":"ImageObject","inLanguage":"sq","@id":"https:\/\/kicevo.gov.mk\/sq\/#\/schema\/logo\/image\/","url":"https:\/\/kicevo.gov.mk\/wp-content\/uploads\/2025\/11\/logo-alb.png","contentUrl":"https:\/\/kicevo.gov.mk\/wp-content\/uploads\/2025\/11\/logo-alb.png","width":1200,"height":1592,"caption":"Opstina Kicevo"},"image":{"@id":"https:\/\/kicevo.gov.mk\/sq\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"vp_sm":false,"vp_md":false,"vp_lg":false,"vp_xl":false,"vp_sm_popup":false,"vp_md_popup":false,"vp_xl_popup":false},"uagb_author_info":{"display_name":"Marina","author_link":"https:\/\/kicevo.gov.mk\/sq\/author\/adminmsb\/"},"uagb_comment_info":0,"uagb_excerpt":"Formular\u00ebtFletorja Zyrtare","_links":{"self":[{"href":"https:\/\/kicevo.gov.mk\/sq\/wp-json\/wp\/v2\/pages\/4886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kicevo.gov.mk\/sq\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kicevo.gov.mk\/sq\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kicevo.gov.mk\/sq\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kicevo.gov.mk\/sq\/wp-json\/wp\/v2\/comments?post=4886"}],"version-history":[{"count":4,"href":"https:\/\/kicevo.gov.mk\/sq\/wp-json\/wp\/v2\/pages\/4886\/revisions"}],"predecessor-version":[{"id":17316,"href":"https:\/\/kicevo.gov.mk\/sq\/wp-json\/wp\/v2\/pages\/4886\/revisions\/17316"}],"wp:attachment":[{"href":"https:\/\/kicevo.gov.mk\/sq\/wp-json\/wp\/v2\/media?parent=4886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}